{"id":4938,"date":"2026-04-08T11:45:11","date_gmt":"2026-04-08T11:45:11","guid":{"rendered":"https:\/\/www.llullsastre.com\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/"},"modified":"2026-05-05T09:24:04","modified_gmt":"2026-05-05T09:24:04","slug":"lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer","status":"publish","type":"post","link":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/","title":{"rendered":"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer"},"content":{"rendered":"\n<p>Das Team von Construcciones Llull Sastre SAU hat zusammen mit Melchor Mascar\u00f3 SAU an der Ausf\u00fchrung der Lobster Club Portals mitgewirkt, einem Projekt der Capuccino-Gruppe, das sich durch seine einzigartige Architektur und technische Komplexit\u00e4t auszeichnet, da es direkt auf dem Wellenbrecher des Hafens errichtet wurde.<\/p>\n\n<p>Die Errichtung des Fundaments stellte eine der gr\u00f6\u00dften Herausforderungen des Projekts dar. Zur Stabilisierung des Baugrunds musste ein Teil der bestehenden Steinsch\u00fcttung entfernt und 3,8 Kilometer Mikropf\u00e4hle installiert werden, wobei bis zu 500 Tonnen Zement eingebracht wurden. Das gesamte Fundament wurde sorgf\u00e4ltig abgedichtet, um Beton und Bewehrung vor den Auswirkungen des Meerwassers zu sch\u00fctzen. Zus\u00e4tzlich wurden passive Korrosionsschutzma\u00dfnahmen angewendet.  <\/p>\n\n<p>Von diesem Sockel erheben sich runde und quadratische S\u00e4ulen, die das Obergeschoss tragen, in dem sich eine breite Promenade und das Restaurantgeb\u00e4ude befinden. Besonders bemerkenswert ist das wellenf\u00f6rmige Betondach, entworfen vom Architekturb\u00fcro Morro Serra Morro. Es greift die Form einer Welle auf und erstreckt sich \u00fcber eine geschwungene, von kegelstumpff\u00f6rmigen S\u00e4ulen getragene Wand bis zum Boden. <\/p>\n\n<p>Der Bau dieses Daches erforderte ausschlie\u00dflich Handarbeit. Es wurde eine spezielle Schalung errichtet, auf der alle 60 cm Holzrippen angebracht und durch Querbalken verbunden wurden, wodurch die komplexe dreidimensionale Geometrie entstand. Die gesamte Schalung, sowohl f\u00fcr das Dach als auch f\u00fcr die geschwungenen W\u00e4nde, wurde von Hand gefertigt und unterstreicht die Expertise der Schalungszimmerleute von Siurell Obra Civil.  <\/p>\n\n<p>Das Design wird durch Oberfl\u00e4chenveredelungen abgerundet, die die Integration in die maritime Umgebung unterstreichen. Die Oberseite des Decks weist eine raue Textur und eine sandfarbene F\u00e4rbung auf, die an eine Strandoberfl\u00e4che erinnert, w\u00e4hrend die Unterseite mit TECU\u00ae-Kupferblechen verkleidet ist, die einen aquamarinblauen Farbton annehmen, \u00e4hnlich dem Meeresboden. <\/p>\n\n<p>Das Panoramageb\u00e4ude erstreckt sich \u00fcber den bestehenden Wellenbrecher und f\u00fcgt sich dank seiner geschwungenen Formen und der Anpassung aller Bauelemente \u2013 Pflasterung, Gel\u00e4nder und Holzarbeiten \u2013 an das architektonische Design nahtlos in die Landschaft ein. Das Ergebnis ist ein einzigartiger Ort auf der Insel, der Ingenieurskunst, zeitgen\u00f6ssische Architektur und sorgf\u00e4ltige Handwerkskunst vereint. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein einzigartiges Projekt der Capuccino-Gruppe in Portals, das ein komplexes Fundament auf dem Wellenbrecher mit einem spektakul\u00e4ren Betondach kombiniert, das die Bewegung der Wellen nachbildet.<\/p>\n","protected":false},"author":1,"featured_media":4372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-4938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer - llullsastre..com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer - llullsastre..com\" \/>\n<meta property=\"og:description\" content=\"Ein einzigartiges Projekt der Capuccino-Gruppe in Portals, das ein komplexes Fundament auf dem Wellenbrecher mit einem spektakul\u00e4ren Betondach kombiniert, das die Bewegung der Wellen nachbildet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\" \/>\n<meta property=\"og:site_name\" content=\"llullsastre..com\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T11:45:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T09:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"visualarts.brain@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"visualarts.brain@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\"},\"author\":{\"name\":\"visualarts.brain@gmail.com\",\"@id\":\"https:\/\/www.llullsastre.com\/#\/schema\/person\/9947dc99ef7110824d1fe1b80b5d3902\"},\"headline\":\"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer\",\"datePublished\":\"2026-04-08T11:45:11+00:00\",\"dateModified\":\"2026-05-05T09:24:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\"},\"wordCount\":350,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\",\"url\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\",\"name\":\"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer - llullsastre..com\",\"isPartOf\":{\"@id\":\"https:\/\/www.llullsastre.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp\",\"datePublished\":\"2026-04-08T11:45:11+00:00\",\"dateModified\":\"2026-05-05T09:24:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.llullsastre.com\/#\/schema\/person\/9947dc99ef7110824d1fe1b80b5d3902\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage\",\"url\":\"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp\",\"contentUrl\":\"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp\",\"width\":1300,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.llullsastre.com\/de\/bauunternehmen-auf-mallorca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.llullsastre.com\/#website\",\"url\":\"https:\/\/www.llullsastre.com\/\",\"name\":\"llullsastre..com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.llullsastre.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.llullsastre.com\/#\/schema\/person\/9947dc99ef7110824d1fe1b80b5d3902\",\"name\":\"visualarts.brain@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.llullsastre.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c4d17ea74f096dd3beef0908416be171bccdcc0511f88635e108cd99cdab2e9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c4d17ea74f096dd3beef0908416be171bccdcc0511f88635e108cd99cdab2e9b?s=96&d=mm&r=g\",\"caption\":\"visualarts.brain@gmail.com\"},\"sameAs\":[\"https:\/\/www.llullsastre.com\"],\"url\":\"https:\/\/www.llullsastre.com\/de\/author\/visualarts-braingmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer - llullsastre..com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/","og_locale":"de_DE","og_type":"article","og_title":"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer - llullsastre..com","og_description":"Ein einzigartiges Projekt der Capuccino-Gruppe in Portals, das ein komplexes Fundament auf dem Wellenbrecher mit einem spektakul\u00e4ren Betondach kombiniert, das die Bewegung der Wellen nachbildet.","og_url":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/","og_site_name":"llullsastre..com","article_published_time":"2026-04-08T11:45:11+00:00","article_modified_time":"2026-05-05T09:24:04+00:00","og_image":[{"width":1300,"height":680,"url":"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp","type":"image\/webp"}],"author":"visualarts.brain@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"visualarts.brain@gmail.com","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#article","isPartOf":{"@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/"},"author":{"name":"visualarts.brain@gmail.com","@id":"https:\/\/www.llullsastre.com\/#\/schema\/person\/9947dc99ef7110824d1fe1b80b5d3902"},"headline":"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer","datePublished":"2026-04-08T11:45:11+00:00","dateModified":"2026-05-05T09:24:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/"},"wordCount":350,"commentCount":0,"image":{"@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp","articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/","url":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/","name":"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer - llullsastre..com","isPartOf":{"@id":"https:\/\/www.llullsastre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage"},"image":{"@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp","datePublished":"2026-04-08T11:45:11+00:00","dateModified":"2026-05-05T09:24:04+00:00","author":{"@id":"https:\/\/www.llullsastre.com\/#\/schema\/person\/9947dc99ef7110824d1fe1b80b5d3902"},"breadcrumb":{"@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#primaryimage","url":"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp","contentUrl":"https:\/\/www.llullsastre.com\/wp-content\/uploads\/2026\/03\/Lobster-Club-2-1.webp","width":1300,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/www.llullsastre.com\/de\/lobster-club-portals-ingenieurwesen-und-architektur-direkt-am-meer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.llullsastre.com\/de\/bauunternehmen-auf-mallorca\/"},{"@type":"ListItem","position":2,"name":"Lobster Club Portals: Ingenieurwesen und Architektur direkt am Meer"}]},{"@type":"WebSite","@id":"https:\/\/www.llullsastre.com\/#website","url":"https:\/\/www.llullsastre.com\/","name":"llullsastre..com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.llullsastre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.llullsastre.com\/#\/schema\/person\/9947dc99ef7110824d1fe1b80b5d3902","name":"visualarts.brain@gmail.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.llullsastre.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c4d17ea74f096dd3beef0908416be171bccdcc0511f88635e108cd99cdab2e9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4d17ea74f096dd3beef0908416be171bccdcc0511f88635e108cd99cdab2e9b?s=96&d=mm&r=g","caption":"visualarts.brain@gmail.com"},"sameAs":["https:\/\/www.llullsastre.com"],"url":"https:\/\/www.llullsastre.com\/de\/author\/visualarts-braingmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/posts\/4938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/comments?post=4938"}],"version-history":[{"count":1,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/posts\/4938\/revisions"}],"predecessor-version":[{"id":4939,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/posts\/4938\/revisions\/4939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/media\/4372"}],"wp:attachment":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/media?parent=4938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/categories?post=4938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/tags?post=4938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}