{"id":5066,"date":"2026-02-11T11:25:33","date_gmt":"2026-02-11T11:25:33","guid":{"rendered":"https:\/\/www.llullsastre.com\/werte-und-ethik\/"},"modified":"2026-05-05T10:54:55","modified_gmt":"2026-05-05T10:54:55","slug":"werte-und-ethik","status":"publish","type":"page","link":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/","title":{"rendered":"Werte und Ethik"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5066\" class=\"elementor elementor-5066 elementor-219\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f390077 e-flex e-con-boxed e-con e-parent\" data-id=\"f390077\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9f3bca0 e-con-full e-flex e-con e-child\" data-id=\"9f3bca0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c5d8534 e-con-full e-flex e-con e-child\" data-id=\"c5d8534\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bbd14d elementor-widget elementor-widget-heading\" data-id=\"8bbd14d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Unsere Mission.\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b868d6 elementor-widget elementor-widget-text-editor\" data-id=\"9b868d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"clb-services-custom-section wpb_column vc_column_container vc_col-sm-1 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5a4c8\" class=\"ohio-widget ohio-text-sc\"><p>Das Herzst\u00fcck jedes Projekts sind die Menschen, die daran mitwirken und es zum Leben erwecken. Deshalb steht der Kunde f\u00fcr uns an erster Stelle, und wir stellen ihm ein Team aus dynamischen und engagierten Fachleuten zur Seite, die sich mit vollem Einsatz ihrer Arbeit widmen. <\/p><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_hidden-sm vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1572866710770\"> <\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d23e8c0 elementor-widget elementor-widget-n-accordion\" data-id=\"d23e8c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2200\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2200\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Verpflichtung zur Einhaltung der geltenden und anwendbaren Gesetzgebung <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2200\" class=\"elementor-element elementor-element-5f76ca0 e-con-full e-flex e-con e-child\" data-id=\"5f76ca0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2200\" class=\"elementor-element elementor-element-74b87b2 e-flex e-con-boxed e-con e-child\" data-id=\"74b87b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff29b0 elementor-widget elementor-widget-text-editor\" data-id=\"2ff29b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Es werden keine Gesch\u00e4ftsbeziehungen oder gesch\u00e4ftlichen Aktivit\u00e4ten mit Personen aufgenommen, die Verbindungen zu illegalen kommerziellen Aktivit\u00e4ten haben und\/oder diese f\u00f6rdern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2201\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2201\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Treu und Glauben und Ehrlichkeit <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2201\" class=\"elementor-element elementor-element-09ebe50 e-con-full e-flex e-con e-child\" data-id=\"09ebe50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2201\" class=\"elementor-element elementor-element-286234b e-flex e-con-boxed e-con e-child\" data-id=\"286234b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5359ef9 elementor-widget elementor-widget-text-editor\" data-id=\"5359ef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"1671621685807-6f62de80-e52b\" class=\"accordion-item active\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5c555\" class=\"ohio-widget ohio-text-sc\"><p>Unsere Gesch\u00e4ftsbeziehungen werden mit Klarheit, Objektivit\u00e4t, Ernsthaftigkeit und Ehrlichkeit gef\u00fchrt, um illegales, unethisches oder betr\u00fcgerisches Verhalten zu verhindern.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2202\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2202\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Achtung und Verpflichtung zur Vertraulichkeit personenbezogener Daten <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2202\" class=\"elementor-element elementor-element-ef27047 e-con-full e-flex e-con e-child\" data-id=\"ef27047\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2202\" class=\"elementor-element elementor-element-5415fbf e-flex e-con-boxed e-con e-child\" data-id=\"5415fbf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1bfaf8 elementor-widget elementor-widget-text-editor\" data-id=\"b1bfaf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"1671621685855-0327aaf5-223c\" class=\"accordion-item active\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5c85e\" class=\"ohio-widget ohio-text-sc\"><p>Wir wahren die Vertraulichkeit aller personenbezogenen Daten, auf die wir im Rahmen unserer beruflichen T\u00e4tigkeit zugreifen, auch nach deren Beendigung. Es ist unerl\u00e4sslich, angemessene Sicherheitsma\u00dfnahmen zum Schutz unserer eigenen und der vertraulichen oder personenbezogenen Daten Dritter zu implementieren. <\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2203\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2203\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Respekt vor den Menschen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2203\" class=\"elementor-element elementor-element-3147bb7 e-flex e-con-boxed e-con e-child\" data-id=\"3147bb7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2203\" class=\"elementor-element elementor-element-ed7a08c e-con-full e-flex e-con e-child\" data-id=\"ed7a08c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8758c62 elementor-widget elementor-widget-text-editor\" data-id=\"8758c62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bel\u00e4stigung, Missbrauch, Einsch\u00fcchterung, Respektlosigkeit und mangelnde R\u00fccksichtnahme am Arbeitsplatz sind inakzeptabel und werden nicht toleriert.<\/p><p>Es werden Beziehungen gef\u00f6rdert, die auf Respekt, Partizipation, Gleichberechtigung und Zusammenarbeit basieren, um ein respektvolles Arbeitsumfeld und damit ein positives Arbeitsklima zu schaffen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2204\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2204\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Antikorruptions- und Bestechungspolitik <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2204\" class=\"elementor-element elementor-element-7afcb5d e-flex e-con-boxed e-con e-child\" data-id=\"7afcb5d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2204\" class=\"elementor-element elementor-element-2f17e9f e-con-full e-flex e-con e-child\" data-id=\"2f17e9f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-232c9dd elementor-widget elementor-widget-text-editor\" data-id=\"232c9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5be47\" class=\"ohio-accordion-s\u0441 ohio-widget accordion -text\" data-ohio-accordion=\"true\"><div id=\"1671621685945-6fa106b1-09a5\" class=\"accordion-item\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5ce35\" class=\"ohio-widget ohio-text-sc\"><p>Wir werden jegliche Form von Korruption, Bestechung oder Einflussnahme bei der Aus\u00fcbung beruflicher T\u00e4tigkeiten vermeiden, sei es in der \u00f6ffentlichen Verwaltung oder im privaten Sektor.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3153561 e-con-full e-flex e-con e-child\" data-id=\"3153561\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f2f9c22 e-con-full e-flex e-con e-child\" data-id=\"f2f9c22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a58ec03 elementor-widget elementor-widget-heading\" data-id=\"a58ec03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Vision.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3369b30 elementor-widget elementor-widget-text-editor\" data-id=\"3369b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"clb-services-custom-section wpb_column vc_column_container vc_col-sm-1 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5a4c8\" class=\"ohio-widget ohio-text-sc\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5b553\" class=\"ohio-widget ohio-text-sc\"><p>Die im Laufe unserer Firmengeschichte gesammelte Erfahrung bildet die Grundlage unserer Bauweise. Wir besch\u00e4ftigen Fachkr\u00e4fte, die auf die verschiedenen Bereiche spezialisiert sind, in denen wir t\u00e4tig sind. In all unseren Abl\u00e4ufen ber\u00fccksichtigen wir Verfahren, die eine m\u00f6glichst geringe Umweltbelastung und einen ressourcenschonenden Umgang gew\u00e4hrleisten. Wir verwenden die jeweils geeigneten Materialien f\u00fcr optimale Bauergebnisse.   <\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c267e9 elementor-widget elementor-widget-n-accordion\" data-id=\"6c267e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1130\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1130\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pr\u00e4vention von Arbeitsunf\u00e4llen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1130\" class=\"elementor-element elementor-element-6249f40 e-con-full e-flex e-con e-child\" data-id=\"6249f40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1130\" class=\"elementor-element elementor-element-5782d6b e-flex e-con-boxed e-con e-child\" data-id=\"5782d6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eab0242 elementor-widget elementor-widget-text-editor\" data-id=\"eab0242\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir halten die Bestimmungen der geltenden und anwendbaren Gesetzgebung zur Pr\u00e4vention von Arbeitsunf\u00e4llen ein.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1131\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1131\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Einhaltung von Steuer- und Sozialversicherungsvorschriften <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1131\" class=\"elementor-element elementor-element-a3d5a21 e-con-full e-flex e-con e-child\" data-id=\"a3d5a21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1131\" class=\"elementor-element elementor-element-5523013 e-flex e-con-boxed e-con e-child\" data-id=\"5523013\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5dfffd elementor-widget elementor-widget-text-editor\" data-id=\"a5dfffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"1671621685807-6f62de80-e52b\" class=\"accordion-item active\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5c555\" class=\"ohio-widget ohio-text-sc\"><p>S\u00e4mtliche illegalen Praktiken, die die unrechtm\u00e4\u00dfige Hinterziehung von Steuerzahlungen zum Nachteil der Staatskasse und der zust\u00e4ndigen Sozialversicherung beinhalten, werden vermieden.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1132\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1132\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Transparenz der Finanz- und Buchhaltungsdaten <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1132\" class=\"elementor-element elementor-element-41bff79 e-con-full e-flex e-con e-child\" data-id=\"41bff79\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1132\" class=\"elementor-element elementor-element-7c894d3 e-flex e-con-boxed e-con e-child\" data-id=\"7c894d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7ce23 elementor-widget elementor-widget-text-editor\" data-id=\"1c7ce23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"1671621685855-0327aaf5-223c\" class=\"accordion-item active\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5c85e\" class=\"ohio-widget ohio-text-sc\"><div id=\"1671547098084-c97c2512-73e4\" class=\"accordion-item active\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5dc07\" class=\"ohio-widget ohio-text-sc\"><p>Die wirtschaftlichen und finanziellen Informationen m\u00fcssen die wirtschaftliche, finanzielle und verm\u00f6gensbezogene Realit\u00e4t getreu widerspiegeln, und zwar in \u00dcbereinstimmung mit den allgemein anerkannten Rechnungslegungsgrunds\u00e4tzen und den anwendbaren internationalen Rechnungslegungsstandards.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1133\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1133\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Engagement und Respekt f\u00fcr die Umwelt <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1133\" class=\"elementor-element elementor-element-908121a e-flex e-con-boxed e-con e-child\" data-id=\"908121a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1133\" class=\"elementor-element elementor-element-2873a45 e-con-full e-flex e-con e-child\" data-id=\"2873a45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e815c45 elementor-widget elementor-widget-text-editor\" data-id=\"e815c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ein verantwortungsvoller Umgang mit der Umwelt wird gew\u00e4hrleistet, ebenso wie die Einhaltung der Umweltgesetzgebung und die rationelle Nutzung von Ressourcen. Daher muss jede umweltsch\u00e4digende Handlung vermieden werden. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1134\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1134\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Aufsicht <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1134\" class=\"elementor-element elementor-element-7b8bd82 e-flex e-con-boxed e-con e-child\" data-id=\"7b8bd82\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1134\" class=\"elementor-element elementor-element-2ad2ce2 e-con-full e-flex e-con e-child\" data-id=\"2ad2ce2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b0aedc elementor-widget elementor-widget-text-editor\" data-id=\"9b0aedc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5be47\" class=\"ohio-accordion-s\u0441 ohio-widget accordion -text\" data-ohio-accordion=\"true\"><div id=\"1671621685945-6fa106b1-09a5\" class=\"accordion-item\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5ce35\" class=\"ohio-widget ohio-text-sc\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1671622823543\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5d392\" class=\"ohio-accordion-s\u0441 ohio-widget accordion -text\" data-ohio-accordion=\"true\"><div id=\"1671547098224-54668391-9eb1\" class=\"accordion-item active\"><div class=\"accordion-collapse\"><div class=\"accordion-body\"><div id=\"ohio-custom-698c671e5e10f\" class=\"ohio-widget ohio-text-sc\"><p>Um die vollst\u00e4ndige Einhaltung dieses Ethikkodex zu gew\u00e4hrleisten, muss er in der gesamten Organisation bekannt sein und seine Einhaltung bei Bedarf \u00fcberpr\u00fcfbar sein.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e114c43 e-flex e-con-boxed e-con e-parent\" data-id=\"e114c43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ce529a1 e-con-full e-flex e-con e-child\" data-id=\"ce529a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51f6c1e elementor-widget elementor-widget-heading\" data-id=\"51f6c1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ethikkanal<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24f7a24 e-con-full e-flex e-con e-child\" data-id=\"24f7a24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-401bdb8 elementor-widget elementor-widget-text-editor\" data-id=\"401bdb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"clb-services-custom-section wpb_column vc_column_container vc_col-sm-1 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5a4c8\" class=\"ohio-widget ohio-text-sc\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5f3d6\" class=\"ohio-widget ohio-text-sc\"><p>CONSTRUCCIONES LLULL SASTRE SAU hat in seinem Organisations- und Managementmodell einen Ethikkanal zur Pr\u00e4vention und Aufdeckung von Verhaltensweisen oder Handlungen eingerichtet, die gegen die allgemeinen und\/oder branchenspezifischen Vorschriften versto\u00dfen k\u00f6nnten, die gem\u00e4\u00df dem Strafgesetzbuch gelten, wenn es &#8222;die Pflicht auferlegt, m\u00f6gliche Risiken und Verst\u00f6\u00dfe der Stelle zu melden, die f\u00fcr die \u00dcberwachung des Betriebs und der Einhaltung des Pr\u00e4ventionsmodells zust\u00e4ndig ist&#8220;.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_hidden-sm vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1572866710770\"> <\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d19789 elementor-widget elementor-widget-text-editor\" data-id=\"0d19789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"clb-services-custom-section wpb_column vc_column_container vc_col-sm-1 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5a4c8\" class=\"ohio-widget ohio-text-sc\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5b553\" class=\"ohio-widget ohio-text-sc\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1671636417430 vc_row-has-fill\" data-vc-full-width=\"true\" data-vc-full-width-init=\"true\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5f862\" class=\"ohio-widget ohio-text-sc\"><p>Der Ethikkanal steht allen Mitarbeitern von CONSTRUCCIONES LLULL SASTRE SAU sowie Dritten zur Verf\u00fcgung, die den Ethikausschuss \u00fcber etwaige verfahrenstechnische oder organisatorische Schw\u00e4chen informieren, die zu einem kriminellen Risiko oder zur Begehung oder Unterlassung einer Straftat f\u00fchren k\u00f6nnten.<\/p><p>CONSTRUCCIONES LLULL SASTRE SAU verpflichtet sich zur Wahrung der Vertraulichkeit und Anonymit\u00e4t sowie zum Schutz vor Repressalien gegen\u00fcber allen, die Sachverhalte melden. Die Daten werden nur so lange im System gespeichert, wie es f\u00fcr die Untersuchung der gemeldeten Sachverhalte unbedingt erforderlich ist. In jedem Fall kann CONSTRUCCIONES LLULL SASTRE SAU Ihre personenbezogenen Daten nach Ablauf von drei Monaten ab dem Datum ihrer Eingabe in einem anderen, rechtlich zul\u00e4ssigen Umfeld weiterverarbeiten.  <\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b63374e e-flex e-con-boxed e-con e-parent\" data-id=\"b63374e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cef35f1 e-con-full e-flex e-con e-child\" data-id=\"cef35f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0465fbe elementor-widget elementor-widget-heading\" data-id=\"0465fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senden Sie uns Ihre Beschwerde<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4793a41 e-con-full e-flex e-con e-child\" data-id=\"4793a41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe4731 elementor-widget elementor-widget-text-editor\" data-id=\"cfe4731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"clb-services-custom-section wpb_column vc_column_container vc_col-sm-1 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5a4c8\" class=\"ohio-widget ohio-text-sc\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"ohio-custom-698c671e5f3d6\" class=\"ohio-widget ohio-text-sc\"><div id=\"ohio-custom-698c671e600b4\" class=\"ohio-widget ohio-text-sc\"><p>Hier k\u00f6nnen Sie Fragen zu unserem Ethikkodex stellen oder Vorf\u00e4lle melden, die angeblich gegen die darin festgelegten Grunds\u00e4tze, unsere internen Bestimmungen oder geltende Gesetze versto\u00dfen.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e97cc elementor-widget elementor-widget-button\" data-id=\"40e97cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/llullsastre.canaldenunciasanonimas.com\/home\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ZUGANG<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Unsere Mission. Das Herzst\u00fcck jedes Projekts sind die Menschen, die daran mitwirken und es zum Leben erwecken. Deshalb steht der Kunde f\u00fcr uns an erster Stelle, und wir stellen ihm ein Team aus dynamischen und engagierten Fachleuten zur Seite, die sich mit vollem Einsatz ihrer Arbeit widmen. Verpflichtung zur Einhaltung der geltenden und anwendbaren Gesetzgebung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5066","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 Werte und Ethik | Llull Sastre Bauunternehmen Mallorca<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die Werte und ethischen Grunds\u00e4tze von Llull Sastre: Engagement f\u00fcr Nachhaltigkeit, soziale Verantwortung, Transparenz und Bauqualit\u00e4t bei jedem Projekt auf Mallorca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Werte und Ethik | Llull Sastre Bauunternehmen Mallorca\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die Werte und ethischen Grunds\u00e4tze von Llull Sastre: Engagement f\u00fcr Nachhaltigkeit, soziale Verantwortung, Transparenz und Bauqualit\u00e4t bei jedem Projekt auf Mallorca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/\" \/>\n<meta property=\"og:site_name\" content=\"llullsastre..com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T10:54:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/\",\"url\":\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/\",\"name\":\"\u25b7 Werte und Ethik | Llull Sastre Bauunternehmen Mallorca\",\"isPartOf\":{\"@id\":\"https:\/\/www.llullsastre.com\/#website\"},\"datePublished\":\"2026-02-11T11:25:33+00:00\",\"dateModified\":\"2026-05-05T10:54:55+00:00\",\"description\":\"Entdecken Sie die Werte und ethischen Grunds\u00e4tze von Llull Sastre: Engagement f\u00fcr Nachhaltigkeit, soziale Verantwortung, Transparenz und Bauqualit\u00e4t bei jedem Projekt auf Mallorca.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.llullsastre.com\/de\/bauunternehmen-auf-mallorca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Werte und Ethik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.llullsastre.com\/#website\",\"url\":\"https:\/\/www.llullsastre.com\/\",\"name\":\"llullsastre..com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.llullsastre.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Werte und Ethik | Llull Sastre Bauunternehmen Mallorca","description":"Entdecken Sie die Werte und ethischen Grunds\u00e4tze von Llull Sastre: Engagement f\u00fcr Nachhaltigkeit, soziale Verantwortung, Transparenz und Bauqualit\u00e4t bei jedem Projekt auf Mallorca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/","og_locale":"de_DE","og_type":"article","og_title":"\u25b7 Werte und Ethik | Llull Sastre Bauunternehmen Mallorca","og_description":"Entdecken Sie die Werte und ethischen Grunds\u00e4tze von Llull Sastre: Engagement f\u00fcr Nachhaltigkeit, soziale Verantwortung, Transparenz und Bauqualit\u00e4t bei jedem Projekt auf Mallorca.","og_url":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/","og_site_name":"llullsastre..com","article_modified_time":"2026-05-05T10:54:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/","url":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/","name":"\u25b7 Werte und Ethik | Llull Sastre Bauunternehmen Mallorca","isPartOf":{"@id":"https:\/\/www.llullsastre.com\/#website"},"datePublished":"2026-02-11T11:25:33+00:00","dateModified":"2026-05-05T10:54:55+00:00","description":"Entdecken Sie die Werte und ethischen Grunds\u00e4tze von Llull Sastre: Engagement f\u00fcr Nachhaltigkeit, soziale Verantwortung, Transparenz und Bauqualit\u00e4t bei jedem Projekt auf Mallorca.","breadcrumb":{"@id":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.llullsastre.com\/de\/werte-und-ethik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.llullsastre.com\/de\/bauunternehmen-auf-mallorca\/"},{"@type":"ListItem","position":2,"name":"Werte und Ethik"}]},{"@type":"WebSite","@id":"https:\/\/www.llullsastre.com\/#website","url":"https:\/\/www.llullsastre.com\/","name":"llullsastre..com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.llullsastre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/pages\/5066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/comments?post=5066"}],"version-history":[{"count":1,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/pages\/5066\/revisions"}],"predecessor-version":[{"id":5067,"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/pages\/5066\/revisions\/5067"}],"wp:attachment":[{"href":"https:\/\/www.llullsastre.com\/de\/wp-json\/wp\/v2\/media?parent=5066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}